{"id":18246,"date":"2022-09-22T09:48:03","date_gmt":"2022-09-22T09:48:03","guid":{"rendered":"http:\/\/misemhomes.com\/?p=18246"},"modified":"2023-08-22T15:01:23","modified_gmt":"2023-08-22T12:01:23","slug":"about-alanya","status":"publish","type":"post","link":"https:\/\/misemhomes.com\/de\/om-alanya\/about-alanya\/","title":{"rendered":"Entdecken Sie Alanya"},"content":{"rendered":"<p><strong>Alanya<\/strong><\/p>\n<p>Alanya, fr\u00fcher bekannt als Alaiye, ist ein Badeort und ein Bezirk in der t\u00fcrkischen Provinz Antalya. Es liegt an der S\u00fcdk\u00fcste der t\u00fcrkischen Mittelmeerregion, etwa 133 Kilometer (83 Meilen) \u00f6stlich von Antalya. Laut der Volksz\u00e4hlung von 2010 hat die Stadt eine Bev\u00f6lkerung von rund 98.627 Menschen, der Bezirk einschlie\u00dflich der Stadt und ihres Umlandes hat eine Einwohnerzahl von 248.286.<\/p>\n<p>Alanya hat eine reiche Geschichte und war im Laufe der Jahrhunderte eine bedeutende Hochburg verschiedener Mittelmeerreiche, darunter des Ptolem\u00e4er-, Seleukiden-, R\u00f6mischen, Byzantinischen und Osmanischen Reiches. Die strategische Lage der Stadt auf einer kleinen Halbinsel im Mittelmeer, umgeben vom Taurusgebirge, hat zu ihrer historischen Bedeutung beigetragen. Viele Wahrzeichen in Alanya, wie der K\u0131z\u0131l Kule (Roter Turm), Tersane (Werft) und die Burg von Alanya, wurden w\u00e4hrend der Herrschaft von Alaeddin Kayqubad I., einem seldschukischen Sultan, im Mittelalter erbaut.<\/p>\n<p>Heute ist Alanya ein beliebtes Touristenziel, das f\u00fcr sein mediterranes Klima, seine Naturattraktionen und sein historisches Erbe bekannt ist. Es zieht eine betr\u00e4chtliche Anzahl von Touristen an und macht neun Prozent des t\u00fcrkischen Tourismussektors und drei\u00dfig Prozent der ausl\u00e4ndischen Immobilienk\u00e4ufe im Land aus. Die Tourismusbranche erlebt seit 1958 einen Boom, der sie zum dominierenden Wirtschaftszweig der Stadt macht und zu einem Bev\u00f6lkerungswachstum f\u00fchrt. In Alanya finden jedes Jahr bei warmem Wetter Sportveranstaltungen und Kulturfestivals statt.<\/p>\n<p><strong>Namen<\/strong><\/p>\n<p>Die Stadt hat im Laufe der Geschichte mehrere Namens\u00e4nderungen erfahren. In der Antike war es auf Latein als Coracesium und auf Griechisch als Korakesion bekannt. Unter dem Byzantinischen Reich hie\u00df er Kalonoros oder Kalon Oros, was auf Griechisch \u201esch\u00f6ner Berg\u201c bedeutet. Die Seldschuken benannten die Stadt in Alaiye um, abgeleitet vom Namen des Sultans Alaeddin Kayqubad I. Im 13. und 14. Jahrhundert bezeichneten italienische H\u00e4ndler die Stadt als Candelore oder Cardelloro. Der moderne Name \u201eAlanya\u201c wurde 1935 von Mustafa Kemal Atat\u00fcrk eingef\u00fchrt.<\/p>\n<p><strong>Geschichte<\/strong><\/p>\n<p>Weitere Informationen zur mittelalterlichen Beylik-Zeit:\u00a0Alaiye<\/p>\n<div class=\"thumb tleft\">\n<div class=\"thumbinner\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"thumbimage alignnone\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/e3\/Alanya_by_Piri_Reis_color.jpg\/170px-Alanya_by_Piri_Reis_color.jpg\" srcset=\"\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/e3\/Alanya_by_Piri_Reis_color.jpg\/255px-Alanya_by_Piri_Reis_color.jpg 1.5x, \/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/e3\/Alanya_by_Piri_Reis_color.jpg\/340px-Alanya_by_Piri_Reis_color.jpg 2x\" alt=\"A detailed drawing of a map of a distinct peninsula with a walled city, and a curved bay below it. Mountains are included on the right, as is a compass rose on the left.\" width=\"301\" height=\"455\" data-file-width=\"600\" data-file-height=\"909\" \/><\/p>\n<div class=\"thumbcaption\">\n<p>Piri Reis\u00a0Karte von Alanya aus dem Jahr 1525, die die Ausdehnung der mittelalterlichen Stadt und die Lage in der Pamphylia-Ebene zeigt.<\/p>\n<p>Funde in der nahegelegenen Karain-H\u00f6hle deuten auf eine Besiedlung w\u00e4hrend der Altsteinzeit bis zur\u00fcck in das Jahr 20.000 v. Chr. hin, und arch\u00e4ologische Beweise belegen, dass es w\u00e4hrend der Bronzezeit um etwa 3.000 v. Chr. einen Hafen in Syedra s\u00fcdlich der modernen Stadt gab. Eine im Bezirk gefundene ph\u00f6nizische Sprachtafel stammt aus dem Jahr 625 v. Chr., und die Stadt wird ausdr\u00fccklich im griechischen Geographie-Manuskript aus dem 4. Jahrhundert v. Chr., dem Periplus von Pseudo-Scylax, erw\u00e4hnt. Der Burgfelsen war wahrscheinlich unter den Hethitern und dem Ach\u00e4menidenreich bewohnt und wurde erstmals in der hellenistischen Zeit nach der Eroberung des Gebiets durch Alexander den Gro\u00dfen befestigt. Alexanders Nachfolger \u00fcberlie\u00dfen das Gebiet nach Alexanders Tod im Jahr 323 v. Chr. einem der konkurrierenden mazedonischen Gener\u00e4le, Ptolemaios I. Soter. Seine Dynastie behielt lockere Kontrolle \u00fcber die \u00fcberwiegend isaurische Bev\u00f6lkerung und der Hafen wurde zu einem beliebten Zufluchtsort f\u00fcr Mittelmeerpiraten. Die Stadt widerstand Antiochos III. Sein Rivale Antiochus VII. Sidetes schloss 137 v. Chr. die unter Diodot begonnenen Arbeiten an einer neuen Burg und einem neuen Hafen ab.<\/p>\n<p>Die R\u00f6mische Republik k\u00e4mpfte 102 v. Chr. gegen kilikische Piraten, als Marcus Antonius der Redner im nahegelegenen Side ein Prokonsulat errichtete, und 78 v. Chr. unter Servilius Vatia, der die isaurischen St\u00e4mme unter seine Kontrolle brachte. Die Zeit der Piraterie in Alanya endete schlie\u00dflich nach der Eingliederung der Stadt in die Provinz Pamphylien durch Pompeius im Jahr 67 v. Chr. mit der Schlacht von Korakesion im Hafen der Stadt. Nach Strabos Berechnung markierte Coracesium die Grenze zwischen dem antiken Pamphylien und Kilikien (insbesondere Cilicia Trachaea); obwohl andere antike Autoren die Grenze anderswo setzten. Das isaurische Banditentum blieb unter den R\u00f6mern ein Problem, und die St\u00e4mme revoltierten im vierten und f\u00fcnften Jahrhundert n. Chr., wobei der gr\u00f6\u00dfte Aufstand zwischen 404 und 408 stattfand.<\/p>\n<p>Mit der Ausbreitung des Christentums wurde Coracesium, wie es genannt wurde, ein Bistum. Sein Bischof Theodulus nahm am Ersten Konzil von Konstantinopel im Jahr 381 teil, Matidianus am Konzil von Ephesus im Jahr 431, Obrimus am Konzil von Chalkedon im Jahr 451 und Nicephorus (Nicetas) am Dritten Konzil von Konstantinopel im Jahr 680. Coracesium war ein Suffraganbistum des\u00a0Metropolitensitzes\u00a0von Side, der Hauptstadt der\u00a0r\u00f6mischen Provinz\u00a0Pamphylia Prima, zu der Coracesium geh\u00f6rte. Es wurde noch im 12. oder 13. Jahrhundert in der Notitiae Episcopatuum erw\u00e4hnt. Coracesium ist kein Residenzbistum mehr und wird heute von der katholischen Kirche als Titularbistum gef\u00fchrt.<\/p>\n<p>Der Islam kam im 7. Jahrhundert mit arabischen \u00dcberf\u00e4llen auf, die zum Bau neuer Befestigungsanlagen f\u00fchrten. Das Gebiet fiel nach der Schlacht von Manzikert im Jahr 1071 aus der byzantinischen Kontrolle an seldschukische T\u00fcrkenst\u00e4mme und wurde 1120 von Johannes II. Komnenos zur\u00fcckgegeben.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"thumb tright\">\n<div class=\"thumbinner\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21999\" src=\"http:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-3-300x161.jpg\" alt=\"\" width=\"360\" height=\"193\" srcset=\"https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-3-300x161.jpg 300w, https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-3-768x412.jpg 768w, https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-3.jpg 1000w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/p>\n<div class=\"thumbcaption\">\n<p><strong>Statue von Kayqubad I. in Alanya<\/strong><\/p>\n<p>Nach dem Angriff des Vierten Kreuzzugs auf die Byzantiner hielt das christlich-armenische K\u00f6nigreich Kilikien regelm\u00e4\u00dfig den Hafen, und von einem Armenier, Kir Fard, \u00fcbernahmen die T\u00fcrken 1221 die dauerhafte Kontrolle, als der anatolische Seldschuken-Sultan Alaeddin Kayqubad I. ihn eroberte und ihm zuwies der ehemalige Herrscher, dessen Tochter er heiratete, \u00fcbernahm die Leitung der Stadt Ak\u015fehir. Unter der Herrschaft der Seldschuken erlebte die Stadt ihr goldenes Zeitalter und sie kann als Winterhauptstadt ihres Reiches betrachtet werden. Bauprojekte, darunter die Zwillingszitadelle, die Stadtmauern, das Arsenal und K\u0131z\u0131l Kule, machten es zu einem wichtigen Seehafen f\u00fcr den Handel im westlichen Mittelmeerraum, insbesondere mit dem ayyubidischen \u00c4gypten und den italienischen Stadtstaaten. Alaeddin Kayqubad I. errichtete au\u00dferdem zahlreiche G\u00e4rten und Pavillons au\u00dferhalb der Mauern, und viele seiner Werke sind noch immer in der Stadt zu finden. Diese wurden wahrscheinlich aus seiner eigenen Staatskasse und von den \u00f6rtlichen Emire finanziert und vom Bauunternehmer Abu &#8218;Ali al-Kattani al-Halabi errichtet. Der Sohn von Alaeddin Kayqubad I., Sultan G\u0131yaseddin Keyh\u00fcsrev II., setzte die Baukampagne 1240 mit einer neuen Zisterne fort.<\/p>\n<p>In der Schlacht von K\u00f6se Da\u011f im Jahr 1243 brachen die mongolischen Horden die seldschukische Hegemonie in Anatolien. Alanya war damals einer Reihe von Invasionen anatolischer Beyliks ausgesetzt. Lusignaner aus Zypern st\u00fcrzten 1371 kurzzeitig die damals herrschende Hamididen-Dynastie. Die Karamaniden verkauften die Stadt 1427 f\u00fcr 5.000 Goldm\u00fcnzen an die Mamluken \u00c4gyptens, f\u00fcr eine Zeit lang, bevor General Gedik Ahmed Pascha sie 1471 in das wachsende Osmanische Reich eingliederte. Die Stadt wurde zur Hauptstadt eines lokalen Sanjak im Eyalet von I\u00e7el. Die Osmanen weiteten ihre Herrschaft im Jahr 1477 aus, als sie den wichtigsten Schifffahrtshandel,\u00a0Holz, der damals gr\u00f6\u00dftenteils von Venezianern betrieben wurde, unter das\u00a0Regierungsmonopol brachten. Am 6. September 1608 wehrte die Stadt einen Seeangriff des Stephanusordens aus dem Herzogtum Florenz ab.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"thumb tleft\">\n<div class=\"thumbinner\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-22001\" src=\"http:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-300x169.png 300w, https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-1024x576.png 1024w, https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-768x432.png 768w, https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a.png 1072w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div class=\"thumbcaption\">\n<p><strong>Zur Zeit der Seldschuken war Tersane ein Trockendock f\u00fcr Schiffe.<\/strong><\/p>\n<p>Der Handel in der Region wurde durch die Entwicklung einer Meeresroute von Europa um Afrika nach Indien negativ beeinflusst, und in den Steuerregistern des sp\u00e4ten 16. Jahrhunderts wurde Alanya nicht als st\u00e4dtisches Zentrum eingestuft. Im Jahr 1571 erkl\u00e4rten die Osmanen die Stadt als Teil der neu eroberten Provinz Zypern. Die Eroberung verringerte die wirtschaftliche Bedeutung des Hafens von Alanya weiter. Der Reisende Evliya \u00c7elebi besuchte die Stadt 1671\/1672 und schrieb \u00fcber den Erhalt der Burg von Alanya, aber auch \u00fcber den Verfall der Vororte von Alanya. Die Stadt wurde 1864 unter Konya und 1868 unter Antalya aufgeteilt, so wie sie heute ist. Im 18. und 19. Jahrhundert wurden in der Stadt zahlreiche Villen vom osmanischen Adel gebaut, und der zivile Bau wurde unter der \u00f6rtlichen dynastischen Karamaniden-Beh\u00f6rde fortgesetzt. Mitte des 19. Jahrhunderts waren Banditen in der Provinz Antalya wieder weit verbreitet.<\/p>\n<p>Nach dem Ersten Weltkrieg wurde Alanya im Abkommen von St.-Jean-de-Maurienne von 1917 an Italien nominell aufgeteilt, bevor es 1923 im Vertrag von Lausanne zur T\u00fcrkischen Republik zur\u00fcckkehrte. Wie andere in dieser Region litt die Stadt stark unter dem Krieg und dem Bev\u00f6lkerungsaustausch, der die T\u00fcrkische Republik ank\u00fcndigte, als viele Christen der Stadt nach Nea Ionia au\u00dferhalb von Athen umsiedelten. Bei der osmanischen Volksz\u00e4hlung von 1893 wurde die Zahl der Griechen in der Stadt mit 964 bei einer Gesamtbev\u00f6lkerung von 37.914 angegeben. Der Tourismus in der Region begann unter T\u00fcrken, die in den 1960er Jahren wegen der angeblich heilenden Wirkung der Damlata\u015f-H\u00f6hle nach Alanya kamen, und sp\u00e4ter konnte sich die Stadt durch den Zugang zum Flughafen Antalya im Jahr 1998 zu einem internationalen Ferienort entwickeln. Das starke Bev\u00f6lkerungswachstum in den 1990er Jahren war eine Folge der Zuwanderung in die Stadt und f\u00fchrte zu einer raschen Modernisierung der Infrastruktur.<\/p>\n<p><strong>Erdkunde<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"thumb tright\">\n<div class=\"thumbinner\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"thumbimage\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/d\/dc\/Alanya_map.svg\/170px-Alanya_map.svg.png\" srcset=\"\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/d\/dc\/Alanya_map.svg\/255px-Alanya_map.svg.png 1.5x, \/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/d\/dc\/Alanya_map.svg\/340px-Alanya_map.svg.png 2x\" alt=\"\" width=\"272\" height=\"309\" data-file-width=\"1500\" data-file-height=\"1704\" \/><\/p>\n<p>Karte der Alanya-Halbinsel<\/p>\n<p>Geografisch liegt Alanya am Golf von Antalya, umgeben vom Taurusgebirge im Norden und dem Mittelmeer im S\u00fcden. Es nimmt etwa 70 Kilometer K\u00fcstenlinie ein und ist Teil der T\u00fcrkischen Riviera. Die Stadt grenzt an den Bezirk Manavgat entlang der K\u00fcste, das G\u00fcndo\u011fmu\u015f-Gebirge im Landesinneren und andere Bezirke in den Provinzen Konya und Karaman.<\/p>\n<p>Die Pamphylia-Ebene zwischen dem Meer und den Bergen ist ein isoliertes Beispiel eines Nadel-, Hartlaub- und Laubwaldes im \u00f6stlichen Mittelmeerraum, zu dem Libanon-Zeder, immergr\u00fcnes Gestr\u00fcpp, Feigenb\u00e4ume und Schwarzkiefer geh\u00f6ren. Das Alanya-Massiv bezieht sich auf das Gebiet metamorpher Gesteine \u00f6stlich von Antalya. Diese Formation ist vom niedrigsten zum h\u00f6chsten in drei Schichten unterteilt: Mahmutlar, Sug\u00f6z\u00fc und Yumruda\u011f. Die \u00e4hnliche Lithologie erstreckt sich in einem tektonischen Fenster unter der Stadt. Bauxit, ein Aluminiumerz, kommt im Gebiet n\u00f6rdlich der Stadt h\u00e4ufig vor und kann abgebaut werden.<\/p>\n<\/div>\n<\/div>\n<div class=\"thumb tleft\">\n<div class=\"thumbinner\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22003 alignleft\" src=\"http:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-5-300x168.jpg\" alt=\"\" width=\"248\" height=\"139\" srcset=\"https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-5-300x168.jpg 300w, https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-5-1024x573.jpg 1024w, https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-5-768x430.jpg 768w, https:\/\/misemhomes.com\/wp-content\/uploads\/2022\/09\/a-5.jpg 1500w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/p>\n<div class=\"thumbcaption\">\n<p>Spitze der Alanya-Halbinsel<br \/>\nDie Stadt wird von Ost nach West durch eine felsige Halbinsel geteilt, die das charakteristische Merkmal der Stadt darstellt. Der Hafen, das Stadtzentrum und der nach Sultan Kayqubad I. benannte Keykubat-Strand liegen auf der Ostseite der Halbinsel. Der Damlata\u015f-Strand, benannt nach den ber\u00fchmten \u201eTropfh\u00f6hlen\u201c, und der Kleopatra-Strand liegen im Westen. Der Name \u201eKleopatra\u201c leitet sich m\u00f6glicherweise entweder vom Besuch der ptolem\u00e4ischen Prinzessin hier oder von der Einbeziehung der Gegend in ihre Mitgift an Markus Antonius ab. Atat\u00fcrk Bulvar\u0131, der Hauptboulevard, verl\u00e4uft parallel zum Meer und trennt die s\u00fcdliche, viel touristischere Seite von Alanya von der n\u00f6rdlichen, einheimischeren Seite, die sich nach Norden in die Berge erstreckt. Die Ring Road Street, eine weitere Hauptstra\u00dfe, umgibt den Hauptort im Norden.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Klima<\/strong><\/p>\n<p>Alanya hat ein mediterranes Hei\u00dfsommerklima mit langen, hei\u00dfen und trockenen Sommern und milden, feuchten Wintern. Die Anwesenheit des Taurusgebirges verursacht Nebel, der an vielen Morgen sichtbare Regenb\u00f6gen erzeugt. Die Meerestemperatur in Alanya betr\u00e4gt durchschnittlich 21,4\u00b0C (71\u00b0F) pro Jahr, wobei der August der w\u00e4rmste Monat ist.<\/p>\n<p>Alanya bietet eine Kombination aus nat\u00fcrlicher Sch\u00f6nheit, historischen St\u00e4tten und einer lebendigen Tourismusbranche und ist damit ein beliebtes Reiseziel f\u00fcr Besucher aus der ganzen Welt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Alanya Alanya, fr\u00fcher bekannt als Alaiye, ist ein Badeort und ein Bezirk in der t\u00fcrkischen Provinz Antalya. Es liegt an der S\u00fcdk\u00fcste der t\u00fcrkischen Mittelmeerregion, etwa 133 Kilometer (83 Meilen) \u00f6stlich von Antalya. Laut der Volksz\u00e4hlung von 2010 hat die Stadt eine Bev\u00f6lkerung von rund 98.627 Menschen, der Bezirk einschlie\u00dflich der Stadt und ihres Umlandes [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[110],"tags":[],"class_list":["post-18246","post","type-post","status-publish","format-standard","hentry","category-om-alanya"],"_links":{"self":[{"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/posts\/18246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/comments?post=18246"}],"version-history":[{"count":3,"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/posts\/18246\/revisions"}],"predecessor-version":[{"id":32987,"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/posts\/18246\/revisions\/32987"}],"wp:attachment":[{"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/media?parent=18246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/categories?post=18246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/misemhomes.com\/de\/wp-json\/wp\/v2\/tags?post=18246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}